{"id":26,"count":35,"description":"Tudo sobre Educa\u00e7\u00e3o e Escolas em Sorocaba. Veja dicas, avalia\u00e7\u00f5es, mapas, telefone, endere\u00e7o dos locais.","link":"https:\/\/www.encontrasorocaba.com.br\/sobre\/educacao-em-sorocaba\/","name":"Educa\u00e7\u00e3o Sorocaba","slug":"educacao-em-sorocaba","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.encontrasorocaba.com.br\/sobre\/wp-json\/wp\/v2\/categories\/26","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.encontrasorocaba.com.br\/sobre\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.encontrasorocaba.com.br\/sobre\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.encontrasorocaba.com.br\/sobre\/wp-json\/wp\/v2\/posts?categories=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}